{"id":1030885,"date":"2026-02-15T23:00:00","date_gmt":"2026-02-15T23:00:00","guid":{"rendered":""},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T00:00:00","slug":"trans-27049-9","status":"publish","type":"post","link":"https:\/\/infoans.news\/es\/trans-27049-9\/","title":{"rendered":"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional"},"content":{"rendered":"<p>Despu&eacute;s de los saludos de la Madre General de las HMA, Madre Chiara Cazzuola, y del Consejero General para la Formaci&oacute;n de los Salesianos de Don Bosco, padre Silvio Roggia, le&iacute;do por el postulador general para las Causas de los Santos de la Familia Salesiana, padre Pier Luigi Cameroni, los trabajos entraron en el coraz&oacute;n del asunto con las intervenciones de los estudiosos.<\/p>\n<p>La decana del <em>Auxilium<\/em>, profesora hermana Piera Ruffinatto, HMA, analiz&oacute; a fondo las cartas a los j&oacute;venes entre 1870 y 1879, evidenciando el papel constante, pero discreto, de la Virgen Mar&iacute;a en la acci&oacute;n educativa salesiana: no solo figura devocional, sino madre, gu&iacute;a y sost&eacute;n en el recorrido formativo de los j&oacute;venes y de los mismos educadores.<\/p>\n<p>A continuaci&oacute;n, la Salesiana Cooperadora profesora Eloisa De Felice profundiz&oacute; el tema de la relaci&oacute;n entre Don Bosco y las Salesianas Cooperadoras laicas, examinando la correspondencia desde el reconocimiento de la Asociaci&oacute;n de los Salesianos Cooperadores en 1876 hasta la muerte del santo en 1888. Particular atenci&oacute;n fue dedicada al papel de las Salesianas Cooperadoras durante la epidemia de c&oacute;lera de 1884-1886, cuando estuvieron comprometidas en la asistencia a los enfermos por invitaci&oacute;n directa del fundador salesiano.<\/p>\n<p>La ponencia de la profesora Eliana Petri, HMA puso en evidencia la capacidad relacional de Don Bosco con religiosas de diversas congregaciones. El an&aacute;lisis de cerca de noventa cartas evidenci&oacute; la construcci&oacute;n de redes de colaboraci&oacute;n entre institutos religiosos en los a&ntilde;os dif&iacute;ciles de la unificaci&oacute;n italiana, marcados por tensiones entre Estado e Iglesia y por hostilidad hacia las instituciones eclesiales.<\/p>\n<p>Sucesivamente, la profesora Grazia Loparco, HMA profundiz&oacute; la presencia de las Hijas de Mar&iacute;a Auxiliadora en las 4.682 cartas del santo, subrayando c&oacute;mo su papel emerge como estructural en los proyectos educativos y misioneros. De las fuentes epistolares aparece una relaci&oacute;n fundada en colaboraci&oacute;n, autonom&iacute;a operativa y visi&oacute;n estrat&eacute;gica compartida con los salesianos, mientras algunas elecciones organizativas revelan una visi&oacute;n estrat&eacute;gica de gobierno compartido. En el conjunto emerge que el v&iacute;nculo de Don Bosco con las HMA se funda en una visi&oacute;n carism&aacute;tica y educativa com&uacute;n, m&aacute;s que en simples referencias expl&iacute;citas en las cartas.<\/p>\n<p>A cerrar el congreso fue el curador de los diez vol&uacute;menes del Epistolario, padre Francesco Motto, SDB, quien deline&oacute; el perfil humano y espiritual de Don Bosco surgido del corpus de las cartas. En su intervenci&oacute;n record&oacute; los cuarenta a&ntilde;os de trabajo editorial entre dificultades filol&oacute;gicas, descubrimientos documentarios y la progresiva familiaridad con la figura del santo, madurada en el contacto directo con sus escritos.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=vQ13BtJbUrI\">El congreso fue seguido en directo <em>streaming <\/em>por varios centenares de personas<\/a>, sobre todo, pero no solo HMA, conectadas desde diversas partes del mundo, confirmando as&iacute; el inter&eacute;s internacional por la figura, el pensamiento y la obra de Don Bosco.<\/p>\n<p>Todas las ponencias de las diversas presentaciones, en gran parte ya disponibles online, ser&aacute;n editadas dentro de pocos meses en un volumen espec&iacute;fico en la colecci&oacute;n <em>Studi <\/em>del Instituto Hist&oacute;rico Salesiano.<\/p>\n<p><a href=\"https:\/\/drive.google.com\/drive\/u\/1\/folders\/1Klr_m4QWbregohWj-l3H7ulyDYZpDlyX\">Textos en varios idiomas<\/a><\/p>\n<p><strong><\/p>\n<div style=\"padding: 15px; margin: 20px 0; background: #fff3cd; color: #856404; border: 1px solid #ffeeba; border-radius: 5px; font-family: sans-serif; font-size: 14px;\">\n                    <strong>[Gallery Missing]<\/strong> Folder not found: <code>wp-content\/uploads\/images\/Italia - Epistolario da FMA 2026<\/code>\n                <\/div>\n<p><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu&eacute;s de los saludos de la Madre General de las HMA, Madre Chiara Cazzuola, y del Consejero General para la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2027049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"page_builder":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1030885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional - ANS - Agenzia iNfo Salesiana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoans.news\/es\/trans-27049-9\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional - ANS - Agenzia iNfo Salesiana\" \/>\n<meta property=\"og:description\" content=\"Despu&eacute;s de los saludos de la Madre General de las HMA, Madre Chiara Cazzuola, y del Consejero General para la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoans.news\/es\/trans-27049-9\/\" \/>\n<meta property=\"og:site_name\" content=\"ANS - Agenzia iNfo Salesiana\" \/>\n<meta property=\"article:published_time\" content=\"-0001-11-30T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/afbea3eb3026ad29e16bf7f9326b894c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"root\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"root\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/\"},\"author\":{\"name\":\"root\",\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\"},\"headline\":\"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional\",\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/\"},\"wordCount\":609,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/afbea3eb3026ad29e16bf7f9326b894c.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/\",\"url\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/\",\"name\":\"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional - ANS - Agenzia iNfo Salesiana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/afbea3eb3026ad29e16bf7f9326b894c.jpg\",\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/afbea3eb3026ad29e16bf7f9326b894c.jpg\",\"contentUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/afbea3eb3026ad29e16bf7f9326b894c.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/trans-27049-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/infoans.news\\\/es\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/infoans.news\\\/es\\\/\",\"name\":\"ANS - Agenzia iNfo Salesiana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoans.news\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoans.news\\\/es\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\",\"name\":\"root\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"caption\":\"root\"},\"sameAs\":[\"https:\\\/\\\/infoans.news\\\/\"],\"url\":\"https:\\\/\\\/infoans.news\\\/es\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional - ANS - Agenzia iNfo Salesiana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoans.news\/es\/trans-27049-9\/","og_locale":"es_ES","og_type":"article","og_title":"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional - ANS - Agenzia iNfo Salesiana","og_description":"Despu&eacute;s de los saludos de la Madre General de las HMA, Madre Chiara Cazzuola, y del Consejero General para la [&hellip;]","og_url":"https:\/\/infoans.news\/es\/trans-27049-9\/","og_site_name":"ANS - Agenzia iNfo Salesiana","article_published_time":"-0001-11-30T00:00:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/afbea3eb3026ad29e16bf7f9326b894c.jpg","type":"image\/jpeg"}],"author":"root","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"root","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoans.news\/es\/trans-27049-9\/#article","isPartOf":{"@id":"https:\/\/infoans.news\/es\/trans-27049-9\/"},"author":{"name":"root","@id":"https:\/\/infoans.news\/es\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04"},"headline":"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional","datePublished":"-0001-11-30T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/infoans.news\/es\/trans-27049-9\/"},"wordCount":609,"commentCount":0,"image":{"@id":"https:\/\/infoans.news\/es\/trans-27049-9\/#primaryimage"},"thumbnailUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/afbea3eb3026ad29e16bf7f9326b894c.jpg","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/infoans.news\/es\/trans-27049-9\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/infoans.news\/es\/trans-27049-9\/","url":"https:\/\/infoans.news\/es\/trans-27049-9\/","name":"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional - ANS - Agenzia iNfo Salesiana","isPartOf":{"@id":"https:\/\/infoans.news\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoans.news\/es\/trans-27049-9\/#primaryimage"},"image":{"@id":"https:\/\/infoans.news\/es\/trans-27049-9\/#primaryimage"},"thumbnailUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/afbea3eb3026ad29e16bf7f9326b894c.jpg","datePublished":"-0001-11-30T00:00:00+00:00","author":{"@id":"https:\/\/infoans.news\/es\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04"},"breadcrumb":{"@id":"https:\/\/infoans.news\/es\/trans-27049-9\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoans.news\/es\/trans-27049-9\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infoans.news\/es\/trans-27049-9\/#primaryimage","url":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/afbea3eb3026ad29e16bf7f9326b894c.jpg","contentUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/afbea3eb3026ad29e16bf7f9326b894c.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/infoans.news\/es\/trans-27049-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infoans.news\/es\/home\/"},{"@type":"ListItem","position":2,"name":"Italia \u2013 El Epistolario de Don Bosco nuevamente en el centro de un inter\u00e9s internacional"}]},{"@type":"WebSite","@id":"https:\/\/infoans.news\/es\/#website","url":"https:\/\/infoans.news\/es\/","name":"ANS - Agenzia iNfo Salesiana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoans.news\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/infoans.news\/es\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04","name":"root","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","caption":"root"},"sameAs":["https:\/\/infoans.news\/"],"url":"https:\/\/infoans.news\/es\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/posts\/1030885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/comments?post=1030885"}],"version-history":[{"count":0,"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/posts\/1030885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/media\/2027049"}],"wp:attachment":[{"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/media?parent=1030885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/categories?post=1030885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoans.news\/es\/wp-json\/wp\/v2\/tags?post=1030885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}