{"id":1028002,"date":"2026-05-12T22:00:00","date_gmt":"2026-05-12T22:00:00","guid":{"rendered":""},"modified":"2026-05-13T14:19:06","modified_gmt":"2026-05-13T14:19:06","slug":"colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile","status":"publish","type":"post","link":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/","title":{"rendered":"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile"},"content":{"rendered":"<p><strong>(ANS &ndash; Bogot&agrave;) <\/strong>&ndash; In un movimento chiave per il consolidamento di progetti di impatto sociale nel proprio emisfero, l&rsquo;Ispettoria salesiana &ldquo;San Pietro Claver&rdquo; di Colombia-Bogot&agrave; (COB) ha ricevuto la visita ufficiale di Noel Hodel, Delegato per l&rsquo;America Latina di &ldquo;Don Bosco Jugendhilfe Weltweit&rdquo;, la Procura Missionaria salesiana con sede a Berom&uuml;nster, in Svizzera. Questo incontro tecnico di alto livello aveva lo scopo di verificare e progettare nuove linee di investimento sociale nelle zone pi&ugrave; vulnerabili della capitale colombiana.<\/p>\n<p>Durante i tre giorni di lavori, la delegazione internazionale ha concentrato i propri sforzi su due degli ecosistemi di intervento pi&ugrave; robusti dell&rsquo;organizzazione: la &ldquo;Fundaci&oacute;n Servicio Juvenil&rdquo;, riferimento storico nella risocializzazione dei bambini di strada, e la presencia salesiana &ldquo;Porvenir&rdquo;, nodo strategico di educazione e sviluppo comunitario nel sud di Bogot&agrave;. Il dott. Hodel ha analizzato gli indicatori di successo dei programmi in corso, evidenziando l&rsquo;efficacia del modello educativo salesiano in contesti post-conflitto e di disuguaglianza strutturale.<\/p>\n<p>L&rsquo;asse centrale di questa missione internazionale &egrave; stata l&rsquo;identificazione di opportunit&agrave; per la formulazione di proposte di cooperazione in linea con gli standard di sviluppo sostenibile del Ministero Pubblico della Confederazione Svizzera. La visita non solo ha riaffermato la fiducia reciproca tra le due organizzazioni, ma ha anche gettato le basi per una nuova fase di finanziamento e assistenza tecnica mirata alla formazione tecnica professionale e alla protezione globale dei bambini.<\/p>\n<p>Questo riavvicinamento tra la cooperazione svizzera e l&rsquo;istituzione colombiana sottolinea l&rsquo;importanza delle alleanze transatlantiche per affrontare sfide globali come la povert&agrave; e l&rsquo;esclusione. Con questa visita si apre un nuovo capitolo di speranza per migliaia di giovani che vedono in queste iniziative l&rsquo;opportunit&agrave; di trasformare la loro realt&agrave; e contribuire al progresso della nazione.<\/p>\n<div class=\"k2-extra-fields\" style=\"display:none;\">[{&#8220;id&#8221;:&#8221;4&#8243;,&#8221;value&#8221;:&#8221;<\/p>\n<div class=\\\"icon\\\">\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-facebook \\\"><\\\/i><\\\/a>\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-plus \\\"><\\\/i><\\\/a>\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-twitter \\\"><\\\/i><\\\/a>\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-linkedin\\\"><\\\/i>\\r\\n\\r\\n<\\\/a>\\r\\n<\\\/div>&#8220;}]<\/div>\n","protected":false},"excerpt":{"rendered":"<p>(ANS &ndash; Bogot&agrave;) &ndash; In un movimento chiave per il consolidamento di progetti di impatto sociale nel proprio emisfero, l&rsquo;Ispettoria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2028002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"page_builder":"","footnotes":""},"categories":[87],"tags":[],"class_list":["post-1028002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-procurator"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile - ANS - Agenzia iNfo Salesiana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile - ANS - Agenzia iNfo Salesiana\" \/>\n<meta property=\"og:description\" content=\"(ANS &ndash; Bogot&agrave;) &ndash; In un movimento chiave per il consolidamento di progetti di impatto sociale nel proprio emisfero, l&rsquo;Ispettoria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/\" \/>\n<meta property=\"og:site_name\" content=\"ANS - Agenzia iNfo Salesiana\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:19:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/b56b96149e156373bb8f124e7cc3818d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"root\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"root\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/\"},\"author\":{\"name\":\"root\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\"},\"headline\":\"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile\",\"datePublished\":\"2026-05-12T22:00:00+00:00\",\"dateModified\":\"2026-05-13T14:19:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/\"},\"wordCount\":351,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/b56b96149e156373bb8f124e7cc3818d.jpg\",\"articleSection\":[\"Mission Offices (Procures)\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/\",\"url\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/\",\"name\":\"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile - ANS - Agenzia iNfo Salesiana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/b56b96149e156373bb8f124e7cc3818d.jpg\",\"datePublished\":\"2026-05-12T22:00:00+00:00\",\"dateModified\":\"2026-05-13T14:19:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/b56b96149e156373bb8f124e7cc3818d.jpg\",\"contentUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/b56b96149e156373bb8f124e7cc3818d.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/infoans.news\\\/it\\\/trans-27586-1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/infoans.news\\\/it\\\/\",\"name\":\"ANS - Agenzia iNfo Salesiana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoans.news\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\",\"name\":\"root\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"caption\":\"root\"},\"sameAs\":[\"https:\\\/\\\/infoans.news\\\/\"],\"url\":\"https:\\\/\\\/infoans.news\\\/it\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile - ANS - Agenzia iNfo Salesiana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/","og_locale":"it_IT","og_type":"article","og_title":"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile - ANS - Agenzia iNfo Salesiana","og_description":"(ANS &ndash; Bogot&agrave;) &ndash; In un movimento chiave per il consolidamento di progetti di impatto sociale nel proprio emisfero, l&rsquo;Ispettoria [&hellip;]","og_url":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/","og_site_name":"ANS - Agenzia iNfo Salesiana","article_published_time":"2026-05-12T22:00:00+00:00","article_modified_time":"2026-05-13T14:19:06+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/b56b96149e156373bb8f124e7cc3818d.jpg","type":"image\/jpeg"}],"author":"root","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"root","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#article","isPartOf":{"@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/"},"author":{"name":"root","@id":"https:\/\/infoans.news\/it\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04"},"headline":"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile","datePublished":"2026-05-12T22:00:00+00:00","dateModified":"2026-05-13T14:19:06+00:00","mainEntityOfPage":{"@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/"},"wordCount":351,"commentCount":0,"image":{"@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#primaryimage"},"thumbnailUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/b56b96149e156373bb8f124e7cc3818d.jpg","articleSection":["Mission Offices (Procures)"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/","url":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/","name":"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile - ANS - Agenzia iNfo Salesiana","isPartOf":{"@id":"https:\/\/infoans.news\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#primaryimage"},"image":{"@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#primaryimage"},"thumbnailUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/b56b96149e156373bb8f124e7cc3818d.jpg","datePublished":"2026-05-12T22:00:00+00:00","dateModified":"2026-05-13T14:19:06+00:00","author":{"@id":"https:\/\/infoans.news\/it\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04"},"breadcrumb":{"@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#primaryimage","url":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/b56b96149e156373bb8f124e7cc3818d.jpg","contentUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/b56b96149e156373bb8f124e7cc3818d.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/infoans.news\/it\/colombia-alleanza-strategica-tra-svizzera-e-colombia-per-rafforzare-il-tessuto-sociale-giovanile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infoans.news\/it\/trans-27586-1\/"},{"@type":"ListItem","position":2,"name":"Colombia \u2013 Alleanza Strategica tra Svizzera e Colombia per rafforzare il tessuto sociale giovanile"}]},{"@type":"WebSite","@id":"https:\/\/infoans.news\/it\/#website","url":"https:\/\/infoans.news\/it\/","name":"ANS - Agenzia iNfo Salesiana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoans.news\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/infoans.news\/it\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04","name":"root","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","caption":"root"},"sameAs":["https:\/\/infoans.news\/"],"url":"https:\/\/infoans.news\/it\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/posts\/1028002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/comments?post=1028002"}],"version-history":[{"count":0,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/posts\/1028002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/media\/2028002"}],"wp:attachment":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/media?parent=1028002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/categories?post=1028002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/tags?post=1028002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}