{"id":1028300,"date":"2026-06-08T22:00:00","date_gmt":"2026-06-08T22:00:00","guid":{"rendered":""},"modified":"2026-06-09T13:37:09","modified_gmt":"2026-06-09T13:37:09","slug":"italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco","status":"publish","type":"post","link":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/","title":{"rendered":"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco"},"content":{"rendered":"<p><strong>(ANS &ndash; Torino) <\/strong>&ndash; Sabato 13 giugno 2026, presso la Basilica di Maria Ausiliatrice a Torino, avr&agrave; luogo un incontro con&nbsp;il Card. &Aacute;ngel Fern&aacute;ndez Artime, Pro-prefetto del Dicastero per gli Istituti di Vita Consacrata e le Societ&agrave; di Vita Apostolica e Legato Pontificio per le Basiliche Papali di Assisi, gi&agrave; Rettor Maggiore della Congregazione Salesiana. L&rsquo;appuntamento, in programma alle ore 11:00 (UTC+2), verter&agrave; sulla presentazione del suo ultimo libro-intervista, a cura di don Giuseppe Costa, SDB, dal titolo: <em>&ldquo;Un futuro senza numeri e senza mura&rdquo;<\/em> (edizioni San Paolo).<\/p>\n<p><strong>La presentazione del volume<\/strong><\/p>\n<p>Nella circostanza, Padre Ugo Pozzoli, IMC, Vicario Episcopale per la Vita Consacrata della diocesi di Torino, offrir&agrave; un saluto introduttivo a tutti i presenti; inoltre, al fianco del Cardinale Fern&aacute;ndez Artime, interverranno anche:<\/p>\n<p>&ndash;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; il curatore del volume, don Giuseppe Costa, gi&agrave; Direttore della Libreria Editrice Vaticana e gi&agrave; Co-portavoce della Congregazione Salesiana;<\/p>\n<p>&ndash;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; la giornalista Marina Lomunno, Caporedattrice del settimanale della Diocesi di Torino, &ldquo;La Voce e il Tempo&rdquo;;<\/p>\n<p>&ndash;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; e suor Maria Triglia, Figlia di Maria Ausiliatrice, membro del Consiglio di Presidenza della Vita Consacrata (USMI) della Sicilia.<\/p>\n<p>L&rsquo;appuntamento servir&agrave; anche come peculiare omaggio in ricordo della consacrazione della Basilica di Maria Ausiliatrice a Torino, avvenuta il 9 giugno 1868.<\/p>\n<p>Inoltre, in occasione della presentazione del volume, il Card. &Aacute;ngel Fern&aacute;ndez Artime si render&agrave; disponibile anche per rispondere a delle possibili domande.<\/p>\n<p><strong>I temi del libro<\/strong><\/p>\n<p>Il volume, uscito da poche settimane, affronta in un dialogo schietto e sincero tutti i problemi legati al presente e al futuro della vita religiosa: l&rsquo;inesorabile calo delle vocazioni, soprattutto in Occidente, la qualit&agrave; della formazione, le difficolt&agrave; a vivere e a testimoniare la vita fraterna, la fedelt&agrave; al carisma originario tra attivit&agrave; apostoliche da portare avanti e notevoli difficolt&agrave; economiche&hellip; Sono tutti problemi che indicano una evidente fragilit&agrave;.<\/p>\n<p>Ma, notano gli autori, la vita consacrata pu&ograve; rinascere proprio dalle fragilit&agrave; che sta sperimentando sotto tanti aspetti.&nbsp;Non si deve per&ograve; continuare a identificare la vita religiosa solo con la funzione sociale che ha svolto nel passato (nelle scuole, negli ospedali, o nelle istituzioni di azione sociale). Non soltanto &egrave; un errore, ma &egrave; anche fonte di pessimismo e di chiusura davanti a qualsiasi possibilit&agrave; di cambiamento e trasformazione.<\/p>\n<p>&ldquo;Il futuro della Vita Consacrata, che credo profondamente continuer&agrave; ad esistere, perch&eacute; &egrave; lo Spirito di Dio, e non noi, a sostenerla, non passa n&eacute; per il numero, n&eacute; per le pareti e i muri gi&agrave; costruiti che pensiamo di dover a tutti i costi conservare&hellip; Non esiste, n&eacute; esister&agrave; Vita Consacrata senza donne e uomini profondamente credenti, autenticamente espropriati, abbandonati in Dio&rdquo; afferma nel volume il porporato salesiano, il Card. Fern&aacute;ndez Artime.<\/p>\n<p>&ldquo;Oggi la vita religiosa &egrave; pi&ugrave; necessaria che mai, ma ha bisogno di recuperare come non mai l&rsquo;innamoramento e il fascino per il Signore Ges&ugrave;, mettendolo al centro delle nostre vite e nel profondo dei nostri cuori&rdquo;, conclude il Pro-prefetto della DIVCSVA.<\/p>\n<div class=\"k2-extra-fields\" style=\"display:none;\">[{&#8220;id&#8221;:&#8221;4&#8243;,&#8221;value&#8221;:&#8221;<\/p>\n<div class=\\\"icon\\\">\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-facebook \\\"><\\\/i><\\\/a>\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-plus \\\"><\\\/i><\\\/a>\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-twitter \\\"><\\\/i><\\\/a>\\r\\n<a href=\\\"#\\\"><i class=\\\"fa fa-linkedin\\\"><\\\/i>\\r\\n\\r\\n<\\\/a>\\r\\n<\\\/div>&#8220;}]<\/div>\n","protected":false},"excerpt":{"rendered":"<p>(ANS &ndash; Torino) &ndash; Sabato 13 giugno 2026, presso la Basilica di Maria Ausiliatrice a Torino, avr&agrave; luogo un incontro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2028300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"page_builder":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1028300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco - ANS - Agenzia iNfo Salesiana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco - ANS - Agenzia iNfo Salesiana\" \/>\n<meta property=\"og:description\" content=\"(ANS &ndash; Torino) &ndash; Sabato 13 giugno 2026, presso la Basilica di Maria Ausiliatrice a Torino, avr&agrave; luogo un incontro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/\" \/>\n<meta property=\"og:site_name\" content=\"ANS - Agenzia iNfo Salesiana\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-08T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T13:37:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"root\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"root\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/\"},\"author\":{\"name\":\"root\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\"},\"headline\":\"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco\",\"datePublished\":\"2026-06-08T22:00:00+00:00\",\"dateModified\":\"2026-06-09T13:37:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/\"},\"wordCount\":595,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/\",\"url\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/\",\"name\":\"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco - ANS - Agenzia iNfo Salesiana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg\",\"datePublished\":\"2026-06-08T22:00:00+00:00\",\"dateModified\":\"2026-06-09T13:37:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg\",\"contentUrl\":\"https:\\\/\\\/infoans.news\\\/wp-content\\\/uploads\\\/joomla_migration\\\/media\\\/k2\\\/items\\\/src\\\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/infoans.news\\\/it\\\/trans-27129-1\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/infoans.news\\\/it\\\/\",\"name\":\"ANS - Agenzia iNfo Salesiana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infoans.news\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infoans.news\\\/it\\\/#\\\/schema\\\/person\\\/ab88318d0212baf9f68ffd9f1d679c04\",\"name\":\"root\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g\",\"caption\":\"root\"},\"sameAs\":[\"https:\\\/\\\/infoans.news\\\/\"],\"url\":\"https:\\\/\\\/infoans.news\\\/it\\\/author\\\/root\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco - ANS - Agenzia iNfo Salesiana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/","og_locale":"it_IT","og_type":"article","og_title":"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco - ANS - Agenzia iNfo Salesiana","og_description":"(ANS &ndash; Torino) &ndash; Sabato 13 giugno 2026, presso la Basilica di Maria Ausiliatrice a Torino, avr&agrave; luogo un incontro [&hellip;]","og_url":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/","og_site_name":"ANS - Agenzia iNfo Salesiana","article_published_time":"2026-06-08T22:00:00+00:00","article_modified_time":"2026-06-09T13:37:09+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg","type":"image\/jpeg"}],"author":"root","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"root","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#article","isPartOf":{"@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/"},"author":{"name":"root","@id":"https:\/\/infoans.news\/it\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04"},"headline":"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco","datePublished":"2026-06-08T22:00:00+00:00","dateModified":"2026-06-09T13:37:09+00:00","mainEntityOfPage":{"@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/"},"wordCount":595,"commentCount":0,"image":{"@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#primaryimage"},"thumbnailUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg","articleSection":["Uncategorized"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/","url":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/","name":"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco - ANS - Agenzia iNfo Salesiana","isPartOf":{"@id":"https:\/\/infoans.news\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#primaryimage"},"image":{"@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#primaryimage"},"thumbnailUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg","datePublished":"2026-06-08T22:00:00+00:00","dateModified":"2026-06-09T13:37:09+00:00","author":{"@id":"https:\/\/infoans.news\/it\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04"},"breadcrumb":{"@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#primaryimage","url":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg","contentUrl":"https:\/\/infoans.news\/wp-content\/uploads\/joomla_migration\/media\/k2\/items\/src\/99e41d7a47ee071a2ba4b808a7b9d43d.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/infoans.news\/it\/italia-presentazione-del-libro-un-futuro-senza-numeri-e-senza-mura-alla-basilica-maria-ausiliatrice-di-valdocco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infoans.news\/it\/trans-27129-1\/"},{"@type":"ListItem","position":2,"name":"Italia \u2013 Presentazione del libro \u201cUn futuro senza numeri e senza mura\u201d alla Basilica Maria Ausiliatrice di Valdocco"}]},{"@type":"WebSite","@id":"https:\/\/infoans.news\/it\/#website","url":"https:\/\/infoans.news\/it\/","name":"ANS - Agenzia iNfo Salesiana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infoans.news\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/infoans.news\/it\/#\/schema\/person\/ab88318d0212baf9f68ffd9f1d679c04","name":"root","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8df31f9371321641284d378aeb586d5fc658f6ef976788c88ebe945f176d8c65?s=96&d=mm&r=g","caption":"root"},"sameAs":["https:\/\/infoans.news\/"],"url":"https:\/\/infoans.news\/it\/author\/root\/"}]}},"_links":{"self":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/posts\/1028300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/comments?post=1028300"}],"version-history":[{"count":0,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/posts\/1028300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/media\/2028300"}],"wp:attachment":[{"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/media?parent=1028300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/categories?post=1028300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoans.news\/it\/wp-json\/wp\/v2\/tags?post=1028300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}